{"id":8200,"date":"2024-10-24T09:25:50","date_gmt":"2024-10-24T13:25:50","guid":{"rendered":"https:\/\/usaircompressor.com\/?post_type=product&#038;p=8200"},"modified":"2026-05-13T14:55:15","modified_gmt":"2026-05-13T18:55:15","slug":"4000-hp-cycling-air-dryer","status":"publish","type":"product","link":"https:\/\/usaircompressor.com\/es\/producto\/4000-hp-cycling-air-dryer\/","title":{"rendered":"Secador de aire comprimido refrigerado c\u00edclico de 4000 HP | Seca 4200 CFM"},"content":{"rendered":"<ul>\n<li>1 a\u00f1o de garant\u00eda<\/li>\n<li>Ciclismo (se enciende y se apaga cuando es necesario)<\/li>\n<li>Secador de aire refrigerado de ahorro de energ\u00eda<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Secador de aire refrigerante c\u00edclico Punto de roc\u00edo a 100 PSI +40 \u00b0F<br \/>Flujo de aire admisible 4200 CFM a 50 PSI<br \/>Tama\u00f1o de la tuber\u00eda: 8<br \/>1 a\u00f1o de garant\u00eda<\/p>","protected":false},"featured_media":5764,"template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_brand":[],"product_cat":[36],"product_tag":[79,82,81],"class_list":{"0":"post-8200","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-refrigerated-air-dryer","7":"product_tag-air-system-equipment","8":"product_tag-compressed-air-dryer","9":"product_tag-refrigerated-air-dryer","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/usaircompressor.com\/es\/wp-json\/wp\/v2\/product\/8200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/usaircompressor.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/usaircompressor.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/usaircompressor.com\/es\/wp-json\/wp\/v2\/media\/5764"}],"wp:attachment":[{"href":"https:\/\/usaircompressor.com\/es\/wp-json\/wp\/v2\/media?parent=8200"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/usaircompressor.com\/es\/wp-json\/wp\/v2\/product_brand?post=8200"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/usaircompressor.com\/es\/wp-json\/wp\/v2\/product_cat?post=8200"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/usaircompressor.com\/es\/wp-json\/wp\/v2\/product_tag?post=8200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}